{"id":405,"date":"2023-10-14T16:12:30","date_gmt":"2023-10-14T16:12:30","guid":{"rendered":"https:\/\/bonjourlondres.fr\/?p=405"},"modified":"2024-02-28T10:50:23","modified_gmt":"2024-02-28T10:50:23","slug":"tate-obras-modernas","status":"publish","type":"post","link":"https:\/\/bonjourlondres.fr\/es\/tate-modern-oeuvres\/","title":{"rendered":"Obras imprescindibles en la Tate Modern"},"content":{"rendered":"<p>Inaugurado en mayo de 2000, el<strong> Tate Modern<\/strong> cuenta con algunas de las obras de arte m\u00e1s emblem\u00e1ticas de todos los tiempos.<\/p>\n<p>Abarcando m\u00e1s de 100 a\u00f1os de arte, la colecci\u00f3n de la Tate Modern incluye una amplia gama de obras de arte.<\/p>\n<p>Hoy te lo voy a contar todo.<\/p>\n<h2 class=\"summary-title\">Obras de la Tate Modern : resumen del art\u00edculo<\/h2>\n<div class=\"summary-box\">\n<ul class=\"summary-list\">\n<li><a href=\"#_Toc147968150\">Obras de la Tate Modern: Fuente<\/a><\/li>\n<li><a href=\"#_Toc147968151\">Islas Amarillas<\/a><\/li>\n<li><a href=\"#_Toc147968152\">Obras en la Tate Modern: Marilyn<\/a><\/li>\n<li><a href=\"#_Toc147968153\">Un chapuz\u00f3n mayor<\/a><\/li>\n<li><a href=\"#_Toc147968154\">Obras de la Tate Modern: \u00bfTienen que estar desnudas las mujeres para entrar en el Met. Museum?<\/a><\/li>\n<li><a href=\"#_Toc147968155\">Guerra<\/a><\/li>\n<\/ul>\n<\/div>\n<h2><a name=\"_Toc147968150\"><\/a><strong>Obras de la Tate Modern: Fuente<\/strong><\/h2>\n<p>La Fuente de Marcel Duchamp debe de ser una de las obras de arte m\u00e1s emblem\u00e1ticas de todo el siglo XX.<\/p>\n<p>Duchamp cre\u00f3 esta obra utilizando objetos preexistentes y <strong>d\u00e1ndoles un nuevo significado.<\/strong><\/p>\n<p>En esta escultura, transforma el modesto urinario en una obra de arte.<\/p>\n<p>Este concepto tuvo profundas repercusiones a lo largo del siglo XX, allanando el camino al arte conceptual.<\/p>\n<p>Aunque la fuente original se ha perdido, Duchamp hizo esta r\u00e9plica. Actualmente <strong>parte de la colecci\u00f3n de la Tate Modern desde 1964.<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-406\" src=\"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg\" alt=\"obras tate modern\" width=\"1005\" height=\"753\" srcset=\"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg 794w, https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern-300x225.jpg 300w, https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern-768x576.jpg 768w\" sizes=\"(max-width: 1005px) 100vw, 1005px\" \/><\/p>\n<h2><a name=\"_Toc147968151\"><\/a><strong>Islas Amarillas<\/strong><\/h2>\n<p>La Tate Modern posee varias obras importantes del destacado pintor expresionista abstracto Jackson Pollock, <strong>incluidas las Islas Amarillas.<\/strong><\/p>\n<p>Este cuadro pertenece a un grupo de obras que Pollock realiz\u00f3 entre 1951 y 1954 y que denomin\u00f3 \"Vertidos negros\".<\/p>\n<p>En la serie, se aleja de sus anteriores pinturas de goteo coloreadas para adoptar una paleta austera en blanco y negro y un proceso de vertido de pintura negra.<strong> para crear grandes charcos de oscuridad saturada.<\/strong><\/p>\n<h2><a name=\"_Toc147968152\"><\/a><strong>Obras en la Tate Modern: Marilyn<\/strong><\/h2>\n<p>De todos los retratos que el artista pop Andy Warhol hizo de la querida estrella de Hollywood Marilyn Monroe, este austero d\u00edptico de <strong>la colecci\u00f3n de la Tate Modern es seguramente la m\u00e1s conocida.<\/strong><\/p>\n<p>Warhol rindi\u00f3 este homenaje a Marilyn el mismo a\u00f1o despu\u00e9s de su muerte. Cre\u00f3 una serie de grabados repetidos basados en una fotograf\u00eda publicitaria de la actriz de la pel\u00edcula Ni\u00e1gara.<\/p>\n<p>A la izquierda, Warhol representa a Marilyn en color, <strong>mientras que la imagen de la derecha es en blanco y negro.<\/strong><\/p>\n<p>Al contrastar estas dos caras, Warhol pone de relieve la personalidad anta\u00f1o brillante y deslumbrante de la estrella, con la tragedia de su muerte y la inevitable desaparici\u00f3n de su imagen a los ojos del p\u00fablico.<\/p>\n<h2><a name=\"_Toc147968153\"><\/a><strong>Un chapuz\u00f3n mayor<\/strong><\/h2>\n<p>El legendario pintor pop brit\u00e1nico David Hockney cre\u00f3 este impactante cuadro tras mudarse a Los \u00c1ngeles.<\/p>\n<p>Durante su estancia en la ciudad, qued\u00f3 fascinado por el estilo de vida desenfadado y aireado de California, que es <strong>lleg\u00f3 a colorear gran parte de su arte.<\/strong><\/p>\n<p>Este cuadro demuestra la fascinaci\u00f3n de Hockney por las piscinas, s\u00edmbolo m\u00e1ximo del lujo en el Reino Unido, pero un elemento com\u00fan en casi todas las casas de California.<\/p>\n<p>En esta piscina en particular, no se ve a nadie. Sin embargo, podemos <strong>ver la huella de la actividad humana en la salpicadura de agua dejada por un submarinista.<\/strong><\/p>\n<p>El cuadro de Hockney de la colecci\u00f3n de la Tate Modern resume la atm\u00f3sfera lujosa y optimista del arte pop de los a\u00f1os sesenta.<\/p>\n<h2><a name=\"_Toc147968154\"><\/a><strong>Obras de la Tate Modern: \u00bfTienen que estar desnudas las mujeres para entrar en el Met. Museum?<\/strong><\/h2>\n<p>El colectivo art\u00edstico feminista an\u00f3nimo The Guerrilla Girls pas\u00f3 gran parte de la d\u00e9cada de 1980 luchando contra las desigualdades y la discriminaci\u00f3n flagrantes en el mundo. <strong>la infrarrepresentaci\u00f3n de las mujeres en el sector de las artes y los museos.<\/strong><\/p>\n<p>Las campa\u00f1as de carteles sat\u00edricos eran una parte importante de su arte t\u00e1ctico, pues captaban la atenci\u00f3n del p\u00fablico con el mismo texto en negrita, esl\u00f3ganes pegadizos e im\u00e1genes brillantes que la publicidad en los medios de comunicaci\u00f3n de masas.<\/p>\n<p>En esta llamativa obra de arte, incluyen estad\u00edsticas estremecedoras que demuestran cu\u00e1n pocas mujeres artistas <strong>fueron reconocidas en su d\u00eda por el Museo Metropolitano de Nueva York.<\/strong><\/p>\n<h2><a name=\"_Toc147968155\"><\/a><strong>Guerra<\/strong><\/h2>\n<p>La pintora portuguesa Paula Rego lleva varias d\u00e9cadas produciendo cuadros socialmente comprometidos y subversivos, y su obra sigue vigente hoy en d\u00eda.<strong> esta obra de la colecci\u00f3n de la Tate Modern es una de sus m\u00e1s memorables.<\/strong><\/p>\n<p>Realizada en respuesta a un art\u00edculo de peri\u00f3dico que describ\u00eda el estallido de la guerra en Irak, Rego fusiona personajes curiosos y on\u00edricos con elementos terror\u00edficos de sangre y gore.<\/p>\n<p>Es un homenaje a las vidas inocentes que <strong>son inevitablemente destruidos por las brutalidades de la guerra.<\/strong><\/p>\n<p>La galer\u00eda Tate Modern tiene muchas obras por descubrir. Mientras est\u00e9 all\u00ed, no dude en echar un vistazo. Descubrir\u00e1 algunos cuadros famosos y comprometidos. Qu\u00e9 <strong>para deleite de los amantes del arte<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Ouverte en mai 2000, la Tate Modern poss\u00e8de certaines des \u0153uvres d\u2019art les plus embl\u00e9matiques de tous les temps. Couvrant plus de 100 ans d\u2019art, la collection de la Tate Modern comprend une vaste gamme d\u2019\u0153uvres d\u2019art. Aujourd\u2019hui, je vous en parle en d\u00e9tail. Oeuvres Tate Modern : sommaire de l&rsquo;article \u0152uvres du Tate Modern\u00a0: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[3],"tags":[],"class_list":{"0":"post-405","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-londres","8":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les \u0153uvres incontournables du Tate Modern<\/title>\n<meta name=\"description\" content=\"La Tate Modern contient des \u0153uvres incontournables. Ces derni\u00e8res ont marqu\u00e9 l\u2019histoire de l\u2019art de Londres. D\u00e9couvrons-les\u2009!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bonjourlondres.fr\/es\/tate-obras-modernas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les \u0153uvres incontournables du Tate Modern\" \/>\n<meta property=\"og:description\" content=\"La Tate Modern contient des \u0153uvres incontournables. Ces derni\u00e8res ont marqu\u00e9 l\u2019histoire de l\u2019art de Londres. D\u00e9couvrons-les\u2009!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bonjourlondres.fr\/es\/tate-obras-modernas\/\" \/>\n<meta property=\"og:site_name\" content=\"Bonjour Londres\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-14T16:12:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T10:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"794\" \/>\n\t<meta property=\"og:image:height\" content=\"595\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Thibaut\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thibaut\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/\"},\"author\":{\"name\":\"Thibaut\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/#\\\/schema\\\/person\\\/a06a880040108659fb491931035c2ea8\"},\"headline\":\"Les \u0153uvres incontournables du Tate Modern\",\"datePublished\":\"2023-10-14T16:12:30+00:00\",\"dateModified\":\"2024-02-28T10:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/\"},\"wordCount\":844,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonjourlondres.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/oeuvres-tate-modern.jpg\",\"articleSection\":[\"Londres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/\",\"url\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/\",\"name\":\"Les \u0153uvres incontournables du Tate Modern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bonjourlondres.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/oeuvres-tate-modern.jpg\",\"datePublished\":\"2023-10-14T16:12:30+00:00\",\"dateModified\":\"2024-02-28T10:50:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/#\\\/schema\\\/person\\\/a06a880040108659fb491931035c2ea8\"},\"description\":\"La Tate Modern contient des \u0153uvres incontournables. Ces derni\u00e8res ont marqu\u00e9 l\u2019histoire de l\u2019art de Londres. D\u00e9couvrons-les\u2009!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bonjourlondres.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/oeuvres-tate-modern.jpg\",\"contentUrl\":\"https:\\\/\\\/bonjourlondres.fr\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/oeuvres-tate-modern.jpg\",\"width\":794,\"height\":595,\"caption\":\"oeuvres tate modern\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/tate-modern-oeuvres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bonjourlondres.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les \u0153uvres incontournables du Tate Modern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/#website\",\"url\":\"https:\\\/\\\/bonjourlondres.fr\\\/\",\"name\":\"Bonjour Londres\",\"description\":\"Tout pour passer un s\u00e9jour inoubliable en 2026 !\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bonjourlondres.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bonjourlondres.fr\\\/#\\\/schema\\\/person\\\/a06a880040108659fb491931035c2ea8\",\"name\":\"Thibaut\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g\",\"caption\":\"Thibaut\"},\"description\":\"J'aide les voyageurs \u00e0 mieux visiter la ville de Londres avec un contenu \u00e9crit et actualis\u00e9 par des experts locaux pour vivre la meilleure exp\u00e9rience possible ! Notre agence de voyage propose \u00e9galement des visites guid\u00e9es en fran\u00e7ais.\",\"sameAs\":[\"https:\\\/\\\/bonjourlondres.fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obras imprescindibles en la Tate Modern","description":"La Tate Modern contiene obras que no pueden ignorarse. Han dejado su huella en la historia del arte londinense. \u00a1Descubr\u00e1moslas!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bonjourlondres.fr\/es\/tate-obras-modernas\/","og_locale":"es_ES","og_type":"article","og_title":"Les \u0153uvres incontournables du Tate Modern","og_description":"La Tate Modern contient des \u0153uvres incontournables. Ces derni\u00e8res ont marqu\u00e9 l\u2019histoire de l\u2019art de Londres. D\u00e9couvrons-les\u2009!","og_url":"https:\/\/bonjourlondres.fr\/es\/tate-obras-modernas\/","og_site_name":"Bonjour Londres","article_published_time":"2023-10-14T16:12:30+00:00","article_modified_time":"2024-02-28T10:50:23+00:00","og_image":[{"width":794,"height":595,"url":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg","type":"image\/jpeg"}],"author":"Thibaut","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Thibaut","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#article","isPartOf":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/"},"author":{"name":"Thibaut","@id":"https:\/\/bonjourlondres.fr\/#\/schema\/person\/a06a880040108659fb491931035c2ea8"},"headline":"Les \u0153uvres incontournables du Tate Modern","datePublished":"2023-10-14T16:12:30+00:00","dateModified":"2024-02-28T10:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/"},"wordCount":844,"commentCount":0,"image":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#primaryimage"},"thumbnailUrl":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg","articleSection":["Londres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/","url":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/","name":"Obras imprescindibles en la Tate Modern","isPartOf":{"@id":"https:\/\/bonjourlondres.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#primaryimage"},"image":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#primaryimage"},"thumbnailUrl":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg","datePublished":"2023-10-14T16:12:30+00:00","dateModified":"2024-02-28T10:50:23+00:00","author":{"@id":"https:\/\/bonjourlondres.fr\/#\/schema\/person\/a06a880040108659fb491931035c2ea8"},"description":"La Tate Modern contiene obras que no pueden ignorarse. Han dejado su huella en la historia del arte londinense. \u00a1Descubr\u00e1moslas!","breadcrumb":{"@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#primaryimage","url":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg","contentUrl":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern.jpg","width":794,"height":595,"caption":"oeuvres tate modern"},{"@type":"BreadcrumbList","@id":"https:\/\/bonjourlondres.fr\/tate-modern-oeuvres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bonjourlondres.fr\/"},{"@type":"ListItem","position":2,"name":"Les \u0153uvres incontournables du Tate Modern"}]},{"@type":"WebSite","@id":"https:\/\/bonjourlondres.fr\/#website","url":"https:\/\/bonjourlondres.fr\/","name":"Hola Londres","description":"\u00a1Todo lo necesario para pasar unas vacaciones inolvidables en 2026!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bonjourlondres.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/bonjourlondres.fr\/#\/schema\/person\/a06a880040108659fb491931035c2ea8","name":"Thibaut","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/436636a11d7c80b948817b5a66d82f9305017ea4c84ab9a676db1d62ccc2c25d?s=96&d=mm&r=g","caption":"Thibaut"},"description":"Ayudo a los viajeros a aprovechar al m\u00e1ximo su visita a Londres con contenidos escritos y actualizados por expertos locales para que disfruten al m\u00e1ximo de su experiencia. Nuestra agencia de viajes tambi\u00e9n ofrece visitas guiadas en franc\u00e9s.","sameAs":["https:\/\/bonjourlondres.fr"]}]}},"featured_image_src":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern-600x400.jpg","featured_image_src_square":"https:\/\/bonjourlondres.fr\/wp-content\/uploads\/2023\/10\/oeuvres-tate-modern-600x595.jpg","author_info":{"display_name":"Thibaut","author_link":"https:\/\/bonjourlondres.fr\/es\/author\/bonjourlondres\/"},"_links":{"self":[{"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/posts\/405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/comments?post=405"}],"version-history":[{"count":0,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/posts\/405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/media\/406"}],"wp:attachment":[{"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/media?parent=405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/categories?post=405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bonjourlondres.fr\/es\/wp-json\/wp\/v2\/tags?post=405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}